{"id":4863,"date":"2024-02-08T14:41:49","date_gmt":"2024-02-08T12:41:49","guid":{"rendered":"https:\/\/kopar.fi\/?post_type=references&#038;p=4863"},"modified":"2026-08-25T10:40:37","modified_gmt":"2026-08-25T07:40:37","slug":"la-externalizacion-del-mantenimiento-trajo-contaminacion","status":"publish","type":"references","link":"https:\/\/kopar.fi\/es\/referenssit\/yllapidon-ulkoistaminen-toi-saastoja\/","title":{"rendered":"La externalizaci\u00f3n del mantenimiento supuso un ahorro"},"content":{"rendered":"<div class=\"wp-block-cover__container va-container alignfull\">\n<div class=\"wp-block-cover alignfull is-light has-mobile-min-height\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;min-height:66vh;--cover-mobile-min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-white-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-33c85678 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-inner-full-width has-full-width-inner has-no-gap has-reverse-stack is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-basis:50%\"><div class=\"wp-block-cover__container va-container alignfull\">\n<div class=\"wp-block-cover alignfull has-mobile-min-height\" style=\"min-height:66vh;--cover-mobile-min-height:25vh;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1152\" class=\"wp-block-cover__image-background wp-image-925\" alt=\"\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-197.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-197.jpg 2048w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-197-300x169.jpg 300w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-197-1024x576.jpg 1024w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-197-768x432.jpg 768w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-197-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient has-dark-green-fade-up-gradient-background\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-basis:50%\"><div class=\"wp-block-cover__container va-container alignfull\">\n<div class=\"wp-block-cover alignfull has-mobile-min-height\" style=\"min-height:66vh;--cover-mobile-min-height:25vh;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1152\" class=\"wp-block-cover__image-background wp-image-920\" alt=\"\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-145.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-145.jpg 2048w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-145-300x169.jpg 300w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-145-1024x576.jpg 1024w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-145-768x432.jpg 768w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar_bolidenodda-145-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient has-dark-green-fade-up-gradient-background\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n<div class=\"wp-block-columns alignwide has-full-width-inner is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0;padding-right:0px;padding-bottom:0;padding-left:0px;flex-basis:75%\">\n<h1 class=\"wp-block-heading\">La externalizaci\u00f3n del mantenimiento supuso un ahorro<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Los ingenieros de mantenimiento de Kopar viajan a Noruega una vez al a\u00f1o para asegurarse de que las m\u00e1quinas de la fundici\u00f3n de zinc de Boliden en Odda funcionan y el proceso se desarrolla seg\u00fan lo previsto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un contrato de mantenimiento a largo plazo incluye una evaluaci\u00f3n de las necesidades, el mantenimiento anual y las piezas necesarias. El servicio de mantenimiento llave en mano garantiza que el personal de Odda pueda centrarse en lo que mejor sabe hacer: la producci\u00f3n de zinc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Boliden Odda y Kopar empezaron a trabajar juntos hace unos diez a\u00f1os. Kopar ha suministrado a la fundici\u00f3n equipos mec\u00e1nicos de manipulaci\u00f3n de materiales y diversos sistemas de almacenamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Odda subcontrat\u00f3 el mantenimiento a Kopar por motivos econ\u00f3micos. Y como el equipo es de Kopar, lo conocemos mejor que nadie. Es f\u00e1cil conseguir las piezas.<\/p>\n\n\n<div class=\"wp-block-group__container va-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-275b42c8 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group has-white-color has-lime-background-color has-text-color has-background has-link-color wp-elements-c9800d9c2415d46108e4792166d11c5c\" style=\"border-top-left-radius:32px;border-top-right-radius:0px;border-bottom-left-radius:32px;border-bottom-right-radius:32px;margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50);padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\"><div class=\"wp-block-quote__container va-container\">\n<blockquote class=\"wp-block-quote is-style-plain is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-large-font-size wp-block-paragraph\">\"Todos los sistemas que hemos comprado a Kopar han sido de \u00faltima generaci\u00f3n y hemos tenido muy pocos problemas con ellos. Incluso si una m\u00e1quina funciona mal, los ingenieros de Kopar la arreglan inmediatamente.&nbsp;<\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\">Estamos muy satisfechos de que Kopar se haya ocupado de todos los aspectos del mantenimiento y nos haya liberado de esa responsabilidad.\"<\/p>\n<cite><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\"><strong>Kjell Kr\u00e5kevik<\/strong>Director de Mantenimiento de Pasuto de Boliden Odda<\/mark><\/cite><\/blockquote>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top has-white-color has-avocado-background-color has-text-color has-background has-link-color wp-elements-362c75332dd945f3717fde5ed8a180b4 is-layout-flow wp-block-column-is-layout-flow\" style=\"border-top-left-radius:32px;border-bottom-left-radius:32px;border-bottom-right-radius:32px;flex-basis:25%\">\n<h4 class=\"wp-block-heading\">Datos del proyecto<\/h4>\n\n\n\n<section id=\"taxonomy-details-block_4667f16ad71b0efd31b466003cd7486f\" class=\"taxonomy-details\" style=\"--taxonomy-details-bg:transparent;--taxonomy-details-label-color:#d7c94d;--taxonomy-details-term-color:#ffffff;--taxonomy-details-pill-bg:#ffffff;--taxonomy-details-pill-radius:999px;\">\n\t\t\t<ul class=\"taxonomy-details__list\">\n\t\t\t\t\t\t\t<li class=\"taxonomy-details__item\">\n\t\t\t\t\t<div class=\"taxonomy-details__label\">Sector<\/div>\n\t\t\t\t\t<div class=\"taxonomy-details__terms is-text\">Metales y Minerales<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li class=\"taxonomy-details__item\">\n\t\t\t\t\t<div class=\"taxonomy-details__label\">Ubicaci\u00f3n<\/div>\n\t\t\t\t\t<div class=\"taxonomy-details__terms is-text\">Noruega<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\t<\/section>\n<\/div>\n<\/div>\n\n\n\n<section id=\"sisaltolista-block_d486fbb0cb8413dbf132bb45c21dce3d\" class=\"sisaltolista block-sisaltolista alignwide default has-rounded-corners\">\n\t<div class=\"sisaltolista__inner\">\n\t\t\t\t\t<div class=\"sisaltolista__header\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"sisaltolista__section-title\">\u00bfQu\u00e9 inclu\u00eda el paquete?<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"sisaltolista__grid\">\n\t\t\t\t\t\t<article class=\"sisaltolista__item sisaltolista__item--page\">\n\t\t\t<a class=\"sisaltolista__card-link\" href=\"https:\/\/kopar.fi\/es\/mekaaninen-kuljetus\/\">\n\t\t\t\t<span class=\"screen-reader-text\">Transporte mec\u00e1nico<\/span>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"sisaltolista__image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"465\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar-kolakuljetin-744x465.jpg\" class=\"attachment-normal--md size-normal--md\" alt=\"Kopar kolakuljetin\" sizes=\"auto, 100vw\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar-kolakuljetin-744x465.jpg 744w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar-kolakuljetin-1504x940.jpg 1504w\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"sisaltolista__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"sisaltolista__title\">Transporte mec\u00e1nico<\/h3>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"sisaltolista__excerpt\">En la industria de procesos es habitual transportar grandes cantidades de materiales s\u00f3lidos a granel. En este contexto, el transporte mec\u00e1nico es la soluci\u00f3n m\u00e1s sencilla, adecuada tanto para el transporte horizontal como vertical\u2026<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"sisaltolista__button\">Seguir leyendo<\/span>\n\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"sisaltolista__item sisaltolista__item--page\">\n\t\t\t<a class=\"sisaltolista__card-link\" href=\"https:\/\/kopar.fi\/es\/kunnossapitopalvelu\/\">\n\t\t\t\t<span class=\"screen-reader-text\">Servicio de mantenimiento<\/span>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"sisaltolista__image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"465\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar-service-maintenance-744x465.jpg\" class=\"attachment-normal--md size-normal--md\" alt=\"Servicio y mantenimiento de Kopar\" sizes=\"auto, 100vw\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar-service-maintenance-744x465.jpg 744w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/02\/kopar-service-maintenance-1504x940.jpg 1504w\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"sisaltolista__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"sisaltolista__title\">Servicio de mantenimiento<\/h3>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"sisaltolista__excerpt\">Kopar se encarga de tu negocio incluso despu\u00e9s de que tu planta ya est\u00e9 en funcionamiento. Te ofrecemos una gama completa de servicios, desde el servicio de garant\u00eda y el mantenimiento hasta proyectos integrales de modernizaci\u00f3n y desarrollo\u2026.<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"sisaltolista__button\">Seguir leyendo<\/span>\n\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\n\t\t<div class=\"sisaltolista__loading\" aria-hidden=\"true\" hidden>\n\t\t\t<span class=\"sisaltolista__spinner\"><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section id=\"sisaltolista-block_1a2fa6c0f5993ebe80fcbfc2934f99db\" class=\"sisaltolista block-sisaltolista alignwide default highlight_first has-rounded-corners\">\n\t<div class=\"sisaltolista__inner\">\n\t\t\t\t\t<div class=\"sisaltolista__header\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"sisaltolista__section-title\">Echa un vistazo tambi\u00e9n a nuestros otros proyectos<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"sisaltolista__grid\">\n\t\t\t\t\t\t<article class=\"sisaltolista__item sisaltolista__item--references is-highlight\">\n\t\t\t<a class=\"sisaltolista__card-link\" href=\"https:\/\/kopar.fi\/es\/referenssit\/konvertteripolyn-kuljetus-chile\/\">\n\t\t\t\t<span class=\"screen-reader-text\">Transporte del polvo del convertidor<\/span>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"sisaltolista__image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"740\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/200403-codelco-1024x740.jpg\" class=\"attachment-large size-large\" alt=\"\" sizes=\"auto, 100vw\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/200403-codelco-1024x740.jpg 1024w, https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/200403-codelco-300x217.jpg 300w, https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/200403-codelco-768x555.jpg 768w, https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/200403-codelco-1536x1110.jpg 1536w, https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/200403-codelco-2048x1480.jpg 2048w, https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/200403-codelco-18x12.jpg 18w\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"sisaltolista__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"sisaltolista__title\">Transporte del polvo del convertidor<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sisaltolista__terms\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sisaltolista__featured-badge\">Destacado<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/industry\/metallit-mineraalit\/\" class=\"sisaltolista__term\">Metales y minerales<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/plant-type\/sulatot\/\" class=\"sisaltolista__term\">Fundiciones<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/application\/polynkerays-ja-kuljetus\/\" class=\"sisaltolista__term\">Recolecci\u00f3n y transporte de polvo<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/location\/chile\/\" class=\"sisaltolista__term\">Chile<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/location\/etela-amerikka\/\" class=\"sisaltolista__term\">Am\u00e9rica del Sur<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/material\/jaahdyttimien-ja-konverttereiden-poly\/\" class=\"sisaltolista__term\">Polvo en los radiadores y convertidores<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"sisaltolista__excerpt\">En 2026, entregamos dos transportadores de cadenas de arrastre para la recolecci\u00f3n y el transporte de polvo de convertidor metal\u00fargico a una fundici\u00f3n de cobre en Chile. Las condiciones exigentes y las estrictas normas de calidad llevaron a Codelco El Teniente a elegir nuevamente los robustos transportadores de cadena de Kopar, dise\u00f1ados teniendo en cuenta las necesidades espec\u00edficas de las fundiciones. \u00a0<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"sisaltolista__button\">Descubre<\/span>\n\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"sisaltolista__item sisaltolista__item--references\">\n\t\t\t<a class=\"sisaltolista__card-link\" href=\"https:\/\/kopar.fi\/es\/referenssit\/kiintean-hiilen-kasittely-vedyntuotantolaitoksessa\/\">\n\t\t\t\t<span class=\"screen-reader-text\">Tratamiento del carb\u00f3n s\u00f3lido en una planta de producci\u00f3n de hidr\u00f3geno<\/span>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"sisaltolista__image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"465\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/csf_lights_hycamite_kuvaaja_aku-saarenpaa_hycamite-744x465.jpg\" class=\"attachment-normal--md size-normal--md\" alt=\"\" sizes=\"auto, 100vw\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/csf_lights_hycamite_kuvaaja_aku-saarenpaa_hycamite-744x465.jpg 744w, https:\/\/kopar.fi\/wp-content\/uploads\/2026\/08\/csf_lights_hycamite_kuvaaja_aku-saarenpaa_hycamite-1504x940.jpg 1504w\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"sisaltolista__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"sisaltolista__title\">Tratamiento del carb\u00f3n s\u00f3lido en una planta de producci\u00f3n de hidr\u00f3geno<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sisaltolista__terms\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/industry\/kiertotalous\/\" class=\"sisaltolista__term\">Econom\u00eda circular<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/plant-type\/vedyntuotantolaitos\/\" class=\"sisaltolista__term\">Planta de producci\u00f3n de hidr\u00f3geno<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/application\/dekarbonisaatioprosessi\/\" class=\"sisaltolista__term\">Proceso de descarbonizaci\u00f3n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/location\/suomi\/\" class=\"sisaltolista__term\">Finlandia<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/material\/kiintea-hiili\/\" class=\"sisaltolista__term\">Carb\u00f3n s\u00f3lido<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"sisaltolista__excerpt\">Suministramos equipos para el manejo seguro del carb\u00f3n fijo a la planta de producci\u00f3n de hidr\u00f3geno basada en la descomposici\u00f3n del metano m\u00e1s grande de Europa.<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"sisaltolista__button\">Descubre<\/span>\n\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"sisaltolista__item sisaltolista__item--references\">\n\t\t\t<a class=\"sisaltolista__card-link\" href=\"https:\/\/kopar.fi\/es\/referenssit\/kuparipasutteen-kuivaus\/\">\n\t\t\t\t<span class=\"screen-reader-text\">Refrigeraci\u00f3n de calcina de cobre<\/span>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"sisaltolista__image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"465\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar-cooling-drum_-744x465.jpg\" class=\"attachment-normal--md size-normal--md\" alt=\"\" sizes=\"auto, 100vw\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"sisaltolista__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"sisaltolista__title\">Refrigeraci\u00f3n de calcina de cobre<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sisaltolista__terms\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/industry\/metallit-mineraalit\/\" class=\"sisaltolista__term\">Metales y minerales<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/plant-type\/sulatot\/\" class=\"sisaltolista__term\">Fundiciones<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/application\/kuparipasutteen-jaahdytys\/\" class=\"sisaltolista__term\">Refrigeraci\u00f3n de calcina de cobre<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/location\/puola\/\" class=\"sisaltolista__term\">Polonia<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/material\/kuparipasute\/\" class=\"sisaltolista__term\">Trompeta de cobre<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"sisaltolista__excerpt\">El tambor de enfriamiento de la escoria de cobre de la fundici\u00f3n de G\u0142og\u00f3w, de KGHM, se entreg\u00f3 en Polonia en 2016. Al tambor de enfriamiento se le introducen 20 t\/h de calcina de cobre a una temperatura de aproximadamente 450 \u00b0C. El tambor enfr\u00eda el material hasta unos 130 \u00b0C.\u00a0<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"sisaltolista__button\">Descubre<\/span>\n\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"sisaltolista__item sisaltolista__item--references\">\n\t\t\t<a class=\"sisaltolista__card-link\" href=\"https:\/\/kopar.fi\/es\/referenssit\/petihiekan-kuivaus\/\">\n\t\t\t\t<span class=\"screen-reader-text\">Secado de la arena de lecho<\/span>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"sisaltolista__image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"465\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2026\/06\/hiekankuivausrumpu-oki-744x465.jpg\" class=\"attachment-normal--md size-normal--md\" alt=\"\" sizes=\"auto, 100vw\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2026\/06\/hiekankuivausrumpu-oki-744x465.jpg 744w, https:\/\/kopar.fi\/wp-content\/uploads\/2026\/06\/hiekankuivausrumpu-oki-1504x940.jpg 1504w\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"sisaltolista__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"sisaltolista__title\">Secado de la arena de lecho<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sisaltolista__terms\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/industry\/energia-ymparisto\/\" class=\"sisaltolista__term\">Energ\u00eda y Medio Ambiente<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/plant-type\/voimalaitokset\/\" class=\"sisaltolista__term\">Centrales el\u00e9ctricas<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/application\/hiekan-kasittely\/\" class=\"sisaltolista__term\">Tratamiento de la arena<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/location\/indonesia\/\" class=\"sisaltolista__term\">Indonesia<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kopar.fi\/es\/material\/hiekka\/\" class=\"sisaltolista__term\">Arena<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"sisaltolista__excerpt\">En 2015 suministramos por primera vez un tambor de secado de arena de lecho a una central el\u00e9ctrica situada en la selva de Indonesia. El secado se realiza en un tambor giratorio de 1600 mm de di\u00e1metro, al que se introduce la arena h\u00fameda. La energ\u00eda para el secado se genera mediante un quemador de aceite. El secador tiene una longitud de 5000 mm y una capacidad de 5 m\u00b3\/h.\u00a0<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"sisaltolista__button\">Descubre<\/span>\n\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\n\t\t<div class=\"sisaltolista__loading\" aria-hidden=\"true\" hidden>\n\t\t\t<span class=\"sisaltolista__spinner\"><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<div class=\"wp-block-cover__container va-container alignfull\">\n<div class=\"wp-block-cover alignfull is-light has-custom-content-position is-position-center-left\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" class=\"wp-block-cover__image-background wp-image-2831\" alt=\"Jefe de servicio de Kopar\" src=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar_servicemanager_vma.jpg\" style=\"object-position:48% 19%\" data-object-fit=\"cover\" data-object-position=\"48% 19%\" srcset=\"https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar_servicemanager_vma.jpg 1920w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar_servicemanager_vma-300x200.jpg 300w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar_servicemanager_vma-1024x683.jpg 1024w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar_servicemanager_vma-768x512.jpg 768w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar_servicemanager_vma-1536x1024.jpg 1536w, https:\/\/kopar.fi\/wp-content\/uploads\/2023\/03\/kopar_servicemanager_vma-600x400.jpg 600w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-avocado-background-color has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-left is-style-narrow has-lemon-color has-text-color\">\u00bfTiene alg\u00fan desafio que resolver?<\/h2>\n\n\n\n<p class=\"has-text-align-left has-white-color has-text-color wp-block-paragraph\">Deje que le ayudemos. P\u00f3ngase en contacto con nosotros para obtener m\u00e1s informaci\u00f3n sobre nuestros productos y servicios.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"\/fi\/ota-yhteytta\/\">Ponganse en Contacto<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Los ingenieros de mantenimiento viajan a Noruega una vez al a\u00f1o para asegurarse de que la maquinaria de la fundici\u00f3n de zinc de Boliden en Odda funcione correctamente y de que el proceso se desarrolle seg\u00fan lo previsto.<\/p>","protected":false},"featured_media":925,"menu_order":0,"template":"","industry":[396],"plant_type":[409],"application":[],"location":[431],"material":[456],"class_list":["post-4863","references","type-references","status-publish","has-post-thumbnail","hentry","industry-metallit-ja-mineraalit","plant_type-sulatot","location-norja","material-sinkki"],"acf":[],"_links":{"self":[{"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/references\/4863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/references"}],"about":[{"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/types\/references"}],"version-history":[{"count":16,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/references\/4863\/revisions"}],"predecessor-version":[{"id":12427,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/references\/4863\/revisions\/12427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/media\/925"}],"wp:attachment":[{"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/media?parent=4863"}],"wp:term":[{"taxonomy":"industry","embeddable":true,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/industry?post=4863"},{"taxonomy":"plant_type","embeddable":true,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/plant_type?post=4863"},{"taxonomy":"application","embeddable":true,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/application?post=4863"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/location?post=4863"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/kopar.fi\/es\/wp-json\/wp\/v2\/material?post=4863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}